{"id":85337,"date":"2024-11-03T06:31:13","date_gmt":"2024-11-03T06:31:13","guid":{"rendered":"http:\/\/www.tunimedia.tn\/fr\/neymar-de-retour-cest-valide\/"},"modified":"2024-11-03T06:31:13","modified_gmt":"2024-11-03T06:31:13","slug":"neymar-de-retour-cest-valide","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/neymar-de-retour-cest-valide\/","title":{"rendered":"Neymar de retour, c&rsquo;est valid\u00e9 !"},"content":{"rendered":"<p> [ad_1]\n<br \/><img decoding=\"async\" src=\"https:\/\/cdn.football365.fr\/wp-content\/uploads\/se\/2024\/10\/ICONSPORT_179695_0032-1.jpg\" \/><\/p>\n<p>Le club br\u00e9silien de Santos aurait conclu<br \/>\nun accord pour faire revenir Neymar Junior au club en 2025.<\/p>\n<div>\n<p>Le parcours de Neymar vers l\u2019Europe a commenc\u00e9 \u00e0 Santos, o\u00f9 il a<br \/>\nmarqu\u00e9 136 buts en 225 matchs, avant de rejoindre Barcelone, \u00e0<br \/>\nl\u2019\u00e2ge de 21 ans, en 2013.<\/p>\n<p>L\u2019international br\u00e9silien a remport\u00e9 trois titres de champion,<br \/>\nainsi que la Copa Libertadores, avant de choisir de rejoindre la<br \/>\nCatalogne et son lien avec son premier club reste fort.\u00a0Le<br \/>\njoueur de 32 ans serait en train de r\u00e9fl\u00e9chir \u00e0 ses projets<br \/>\nd\u2019avenir apr\u00e8s avoir choisi de rejoindre l\u2019\u00e9quipe de Pro League<br \/>\nsaoudienne Al Hilal en provenance du Paris Saint-Germain en ao\u00fbt<br \/>\n2023.<\/p>\n<h2>Neymar Junior vers un retour aux sources<\/h2>\n<p>Neymar a provisoirement fait son retour \u00e0 l\u2019action, apr\u00e8s une<br \/>\ngrave blessure au genou en octobre 2023, et le pr\u00e9sident de Santos,<br \/>\nMarcelo Teixeira, avait d\u00e9j\u00e0 laiss\u00e9 entendre qu\u2019un retour \u00ab<br \/>\n<em>in\u00e9vitable<\/em> \u00bb \u00e9tait possible.<\/p>\n<p>Depuis, le vice-pr\u00e9sident du conseil d\u2019administration du club,<br \/>\nNico Osvaldo, a confirm\u00e9 que les n\u00e9gociations \u00e9taient presque<br \/>\ntermin\u00e9es, avant une r\u00e9union spectaculaire dans les mois \u00e0<br \/>\nvenir.\u00a0<em>\u00ab Neymar arrivera \u00e0 Santos en juin. C\u2019est la<br \/>\nconversation que nous avons. Il reviendra \u00bb<\/em>, a-t-il<br \/>\nd\u00e9clar\u00e9.<\/p>\n<aside class=\"bloc_resume_post\">\n<h2 class=\"bloc_resume_post_title\">EN BREF<\/h2>\n<ul class=\"bloc_resume_post_list\">\n<li>Neymar, \u00e2g\u00e9 de 32 ans, a rejoint Al Hilal en ao\u00fbt 2023 apr\u00e8s<br \/>\navoir quitt\u00e9 le Paris Saint-Germain.<\/li>\n<li>Apr\u00e8s une blessure au genou en octobre 2023, Neymar envisage un<br \/>\nretour \u00e0 Santos, son club formateur, avec des n\u00e9gociations<br \/>\navanc\u00e9es.<\/li>\n<li>Le vice-pr\u00e9sident de Santos, Nico Osvaldo, a annonc\u00e9 que Neymar<br \/>\nreviendra au club en juin, confirmant les discussions en<br \/>\ncours.<\/li>\n<\/ul>\n<\/aside>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/neymar-de-retour-cest-valide-10210686.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Le club br\u00e9silien de Santos aurait conclu un accord pour faire revenir Neymar Junior au club en 2025. Le parcours de Neymar vers l\u2019Europe a commenc\u00e9 \u00e0 Santos, o\u00f9 il a marqu\u00e9 136 buts en 225 matchs, avant de rejoindre Barcelone, \u00e0 l\u2019\u00e2ge de 21 ans, en 2013. L\u2019international br\u00e9silien a remport\u00e9 trois titres &hellip;<\/p>\n","protected":false},"author":1,"featured_media":84378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-85337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2024\/10\/ICONSPORT_179695_0032-1.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/85337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=85337"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/85337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/84378"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=85337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=85337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=85337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}