{"id":48720,"date":"2022-12-08T20:20:44","date_gmt":"2022-12-08T20:20:44","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/il-a-recu-des-conseils-dune-legende-des-bleus\/"},"modified":"2022-12-08T20:20:44","modified_gmt":"2022-12-08T20:20:44","slug":"il-a-recu-des-conseils-dune-legende-des-bleus","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/il-a-recu-des-conseils-dune-legende-des-bleus\/","title":{"rendered":"il a re\u00e7u des conseils d&rsquo;une l\u00e9gende des Bleus"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nPr\u00e9sent en conf\u00e9rence de presse ce jeudi, Dayot Upamecano a expliqu\u00e9 avoir \u00e9t\u00e9 conseill\u00e9 par un champion du monde 1998. <\/p>\n<div>\n<p>Un devoir de transmission dans les grandes conqu\u00eates. C\u2019est ainsi que l\u2019on pourrait r\u00e9sumer le lien qui unit les champions du monde 1998 \u00e0 leurs successeurs. Dayot Upamecano, qui n\u2019\u00e9tait pas l\u00e0 en 2018, a aussi pu mesurer \u00e0 quel point l\u2019exp\u00e9rience de ses a\u00een\u00e9s \u00e9tait pr\u00e9cieuse.<\/p>\n<h2><span style=\"color: #ff0000;\">Upamecano conseill\u00e9 par une l\u00e9gende !<\/span><\/h2>\n<p>Le d\u00e9fenseur de l\u2019\u00e9quipe de France, excellent depuis le d\u00e9but de cette Coupe du monde, a expliqu\u00e9 avoir eu un guide de choix en la personne de Marcel Desailly, qui l\u2019a conseill\u00e9 sur son jeu.<\/p>\n<p>\u00ab\u00a0<strong>J\u2019ai beaucoup de respect pour Marcel Desailly, on a pu parler ensemble avant les matchs. Il m\u2019a donn\u00e9 des conseils, il m\u2019a dit de continuer comme \u00e7a, \u00e7a fait toujours plaisir, il a \u00e9t\u00e9 un exemple<\/strong>\u00ab\u00a0, a confi\u00e9 le d\u00e9fenseur central du Bayern Munich.<\/p>\n<p>Dayot Upamecano peut \u00e9galement compter sur l\u2019exp\u00e9rience de son comp\u00e8re de d\u00e9fense centrale, Rapha\u00ebl Varane. \u00ab\u00a0<strong>Je suis content de jouer avec Rapha\u00ebl. Il apporte beaucoup \u00e0 l\u2019\u00e9quipe, il me parle beaucoup sur et en dehors du terrain. Je m\u2019entends bien avec tout le monde, que ce soit avec Varane ou Ibou (Konat\u00e9)<\/strong>.\u00a0\u00bb<\/p>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/upamecano-se-confie-il-a-recu-des-conseils-dune-legende-des-bleus-10078789.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Pr\u00e9sent en conf\u00e9rence de presse ce jeudi, Dayot Upamecano a expliqu\u00e9 avoir \u00e9t\u00e9 conseill\u00e9 par un champion du monde 1998. Un devoir de transmission dans les grandes conqu\u00eates. C\u2019est ainsi que l\u2019on pourrait r\u00e9sumer le lien qui unit les champions du monde 1998 \u00e0 leurs successeurs. Dayot Upamecano, qui n\u2019\u00e9tait pas l\u00e0 en 2018, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":48721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-48720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2022\/12\/Dayot-Upamecano-France.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/48720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=48720"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/48720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/48721"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=48720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=48720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=48720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}