{"id":48029,"date":"2022-11-29T23:16:17","date_gmt":"2022-11-29T23:16:17","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/messi-et-pas-que-le-plan-ambitieux-de-beckham-pour-linter-miami\/"},"modified":"2022-11-29T23:16:17","modified_gmt":"2022-11-29T23:16:17","slug":"messi-et-pas-que-le-plan-ambitieux-de-beckham-pour-linter-miami","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/messi-et-pas-que-le-plan-ambitieux-de-beckham-pour-linter-miami\/","title":{"rendered":"Messi et pas que, le plan ambitieux de Beckham pour l\u2019Inter Miami"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nDavid Beckham voit tr\u00e8s grand pour sa franchise am\u00e9ricaine d\u2019Inter Miami. <\/p>\n<div>\n<p>Le propri\u00e9taire de l\u2019Inter de Miami, David Beckham, esp\u00e8re r\u00e9aliser plusieurs acquisitions prestigieuses pour son \u00e9quipe dans les mois \u00e0 venir. <strong>L\u2019Anglais est d\u00e9termin\u00e9 \u00e0 faire grandir l\u2019\u00e9quipe de Floride et la mener vers le sacre en MLS.<\/strong><\/p>\n<h2><span style=\"color: #ff0000;\">Beckham veut trois anciens barcelonais \u00e0 Miami<\/span><\/h2>\n<p>En t\u00eate de sa liste d\u2019achats figure la star du PSG, Lionel Messi, <strong>mais le g\u00e9nie argentin n\u2019est pas son unique cible.<\/strong> Selon le <em>Times<\/em>, le transfert de Messi dans l\u2019\u00e9quipe de Beckham pourrait \u00eatre combin\u00e9 \u00e0 ceux de deux de ses meilleurs amis : Luis Su\u00e1rez et Cesc F\u00e0bregas ; en plus de Sergio Busquets, qui, selon la \u00ab\u00a0Cadena Cope\u00a0\u00bb, a pris la d\u00e9cision de mettre fin \u00e0 sa carri\u00e8re au Bar\u00e7a.<\/p>\n<p>Su\u00e1rez a conclu un accord avec le Nacional pour mettre fin \u00e0 sa relation contractuelle \u00e0 la fin de l\u2019ann\u00e9e, juste apr\u00e8s la fin de la Coupe du monde. Par cons\u00e9quent, <strong>\u00ab\u00a0El Pistolero\u00a0\u00bb sera sans \u00e9quipe lorsque l\u2019\u00e9quipe uruguayenne sera \u00e9limin\u00e9e du tournoi.<\/strong><\/p>\n<p>F\u00e0bregas, quant \u00e0 lui, s\u2019est engag\u00e9 l\u2019\u00e9t\u00e9 dernier \u00e0 Como, en Serie B italienne, o\u00f9 il est sous contrat jusqu\u2019au 30 juin 2024. Cependant, il ne devrait pas y avoir de complication pour le milieu de terrain de quitter son club actuel une saison avant la fin de cet engagement.<\/p>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/messi-plan-ambitieux-de-beckham-linter-miami-10076765.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] David Beckham voit tr\u00e8s grand pour sa franchise am\u00e9ricaine d\u2019Inter Miami. Le propri\u00e9taire de l\u2019Inter de Miami, David Beckham, esp\u00e8re r\u00e9aliser plusieurs acquisitions prestigieuses pour son \u00e9quipe dans les mois \u00e0 venir. L\u2019Anglais est d\u00e9termin\u00e9 \u00e0 faire grandir l\u2019\u00e9quipe de Floride et la mener vers le sacre en MLS. Beckham veut trois anciens barcelonais &hellip;<\/p>\n","protected":false},"author":1,"featured_media":48030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-48029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2022\/11\/PANORAMIC_248519_05591.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/48029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=48029"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/48029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/48030"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=48029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=48029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=48029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}