{"id":47477,"date":"2022-11-23T07:58:12","date_gmt":"2022-11-23T07:58:12","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/mauvaise-nouvelle-confirmee-pour-les-bleus\/"},"modified":"2022-11-23T07:58:12","modified_gmt":"2022-11-23T07:58:12","slug":"mauvaise-nouvelle-confirmee-pour-les-bleus","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/mauvaise-nouvelle-confirmee-pour-les-bleus\/","title":{"rendered":"Mauvaise nouvelle confirm\u00e9e pour les Bleus"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nL&rsquo;\u00e9quipe de France ne pourra plus compter sur Lucas Hernandez jusqu&rsquo;\u00e0 la fin de son parcours en Coupe du monde. <\/p>\n<div>\n<p>Il n\u2019y avait pas de place pour l\u2019espoir. En voyant la mani\u00e8re avec laquelle <strong>Lucas Hernandez<\/strong> a quitt\u00e9 le terrain, <strong>mardi soir lors de France-Australie (4-1)<\/strong>, personne ne pouvait se montrer optimiste. Le d\u00e9fenseur des Bleus ne jouera plus dans cette Coupe du monde 2022, a indiqu\u00e9 la nuit derni\u00e8re la\u00a0F\u00e9d\u00e9ration fran\u00e7aise de football.<\/p>\n<p><strong>Le joueur du Bayern Munich, apr\u00e8s une IRM pass\u00e9e<\/strong>\u00a0\u00e0 la clinique Aspetar, pr\u00e9cise le communiqu\u00e9 de la FFF, souffre d\u2019une \u00ab\u00a0<em>rupture du ligament crois\u00e9 ant\u00e9rieur du genou droit<\/em>.\u00a0\u00bb Ce genre de blessure n\u00e9cessite plusieurs semaines, voire plusieurs mois, de convalescence.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Victime d\u2019une rupture du ligament crois\u00e9 ant\u00e9rieur du genou droit, <a href=\"https:\/\/twitter.com\/LucasHernandez?ref_src=twsrc%5Etfw\">@LucasHernandez<\/a> doit renoncer au Mondial.<\/p>\n<p>Tout le groupe lui souhaite le meilleur r\u00e9tablissement possible &#x1f499;<a href=\"https:\/\/twitter.com\/hashtag\/FiersdetreBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#FiersdetreBleus<\/a> <a href=\"https:\/\/t.co\/TIgHi3qOPJ\">pic.twitter.com\/TIgHi3qOPJ<\/a><\/p>\n<p>\u2014 Equipe de France &#x2b50;&#x2b50; (@equipedefrance) <a href=\"https:\/\/twitter.com\/equipedefrance\/status\/1595216387093430277?ref_src=twsrc%5Etfw\">November 23, 2022<\/a><\/p>\n<\/blockquote>\n<p>Lucas Hernandez s\u2019est<strong> bless\u00e9 d\u00e8s la 9e minute de France-Australie, match d\u2019ouverture des Bleus<\/strong>, en perdant son duel face \u00e0\u00a0Mathew Leckie avant que celui-ci ne trouve\u00a0Craig Goodwin pour l\u2019ouverture du score.<\/p>\n<p>Le natif de Marseille a \u00e9t\u00e9 remplac\u00e9 par son fr\u00e8re, Th\u00e9o, notamment passeur d\u00e9cisif sur l\u2019\u00e9galisation sign\u00e9e Adrien Rabiot (1-1, 27e).<\/p>\n<h2><span style=\"color: #ff0000;\">La liste s\u2019allonge<\/span><\/h2>\n<p>Le s\u00e9lectionneur tricolore Didier Deschamps ne peut pas remplacer Lucas Hernandez et devra se contenter, avec son fr\u00e8re, d\u2019un seul lat\u00e9ral gauche de m\u00e9tier dans son groupe de 25 joueurs.<\/p>\n<p>Les Bleus\u00a0ont d\u00e9j\u00e0 <strong>perdu Paul Pogba, N\u2019Golo Kant\u00e9, Mike Maignan, Presnel Kimpembe, Christopher Nkunku et Karim Benzema.<\/strong><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/coupe-monde-mauvaise-nouvelle-confirmee-bleus-10075137.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] L&rsquo;\u00e9quipe de France ne pourra plus compter sur Lucas Hernandez jusqu&rsquo;\u00e0 la fin de son parcours en Coupe du monde. Il n\u2019y avait pas de place pour l\u2019espoir. En voyant la mani\u00e8re avec laquelle Lucas Hernandez a quitt\u00e9 le terrain, mardi soir lors de France-Australie (4-1), personne ne pouvait se montrer optimiste. Le d\u00e9fenseur &hellip;<\/p>\n","protected":false},"author":1,"featured_media":47478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-47477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2022\/11\/Hernandez.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/47477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=47477"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/47477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/47478"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=47477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=47477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=47477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}