{"id":3789,"date":"2021-04-19T12:59:45","date_gmt":"2021-04-19T12:59:45","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/diminue-al-ahly-gagne-un-spectaculaire-derby\/"},"modified":"2021-04-19T12:59:45","modified_gmt":"2021-04-19T12:59:45","slug":"diminue-al-ahly-gagne-un-spectaculaire-derby","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/diminue-al-ahly-gagne-un-spectaculaire-derby\/","title":{"rendered":"Diminu\u00e9, Al-Ahly gagne un spectaculaire derby"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nBien que diminu\u00e9, Al-Ahly s&rsquo;est offert le derby du Caire face au Zamalek (2-1), ce dimanche soir. <\/p>\n<div>\n<p>Pourtant tr\u00e8s diminu\u00e9 (Ali Maaloul, Mohamed El-Shenawy, Mohamed Hany, Hamdi Fathi et Junior Ajayi manquaient \u00e0 l\u2019appel),<strong> Al-Ahly s\u2019est offert le derby du Caire aux d\u00e9pens du Zamalek (2-1)<\/strong>, dimanche soir. Un doubl\u00e9 de Mohamed Sherif (21e, 34e) a permis aux champions en titre de disposer des Chevaliers Blancs, qui avaient pourtant \u00e9galis\u00e9 sur une frappe sensationnelle du v\u00e9t\u00e9ran Shikabala (31e). Dominateurs durant toute la seconde p\u00e9riode, les hommes de Patrice Carteron ne parvenaient pas \u00e0 \u00e9galiser ensuite. <\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"fr\" dir=\"ltr\">Le Caire est toujours rouge&#x1f534;&#x1f985;<a href=\"https:\/\/twitter.com\/hashtag\/AllezAhly?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezAhly<\/a> <a href=\"https:\/\/t.co\/vdEiGaI5Jx\">pic.twitter.com\/vdEiGaI5Jx<\/a><\/p>\n<p>\u2014 Al Ahly SC &#x1f1eb;&#x1f1f7; (@AlAhlyfrancais) <a href=\"https:\/\/twitter.com\/AlAhlyfrancais\/status\/1383895368954302472?ref_src=twsrc%5Etfw\">April 18, 2021<\/a><\/p>\n<\/blockquote>\n<p>Sur le banc d\u2019Al-Ahly, <strong>Pitso Mosimane <\/strong>pouvait pavoiser. Le Sud-Africain est toujours invaincu en championnat depuis son arriv\u00e9e \u00e0 Al-Ahly fin 2020. Quant au classement du championnat, Zamalek en garde la t\u00eate malgr\u00e9 sa d\u00e9faite. Mais ses trois longueurs d\u2019avance sur leurs tombeurs du jour risquent d\u2019\u00eatre insuffisants, les Diables Rouges comptant trois matchs en moins. <\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/diminue-al-ahly-gagne-spectaculaire-derby-9963608.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Bien que diminu\u00e9, Al-Ahly s&rsquo;est offert le derby du Caire face au Zamalek (2-1), ce dimanche soir. Pourtant tr\u00e8s diminu\u00e9 (Ali Maaloul, Mohamed El-Shenawy, Mohamed Hany, Hamdi Fathi et Junior Ajayi manquaient \u00e0 l\u2019appel), Al-Ahly s\u2019est offert le derby du Caire aux d\u00e9pens du Zamalek (2-1), dimanche soir. Un doubl\u00e9 de Mohamed Sherif (21e, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":3790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-3789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2021\/04\/AHLY_SHERIF_JOIE_180421.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/3789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=3789"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/3789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/3790"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=3789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=3789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=3789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}