{"id":30670,"date":"2022-04-08T07:07:35","date_gmt":"2022-04-08T07:07:35","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/menaces-de-mort-sur-un-gardien-au-bresil\/"},"modified":"2022-04-08T07:07:35","modified_gmt":"2022-04-08T07:07:35","slug":"menaces-de-mort-sur-un-gardien-au-bresil","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/menaces-de-mort-sur-un-gardien-au-bresil\/","title":{"rendered":"Menaces de mort sur un gardien au Br\u00e9sil"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nLe club des Corinthians prend tr\u00e8s au s\u00e9rieux les menaces physiques dont sont victimes son gardien de but et sa famille. <\/p>\n<div>\n<p>Le Br\u00e9silien Cassio Ramos, 34 ans (1 s\u00e9lection), a \u00e9t\u00e9 plac\u00e9 sous protection polici\u00e8re. La situation du gardien de but des Corinthians inqui\u00e8te \u00e9norm\u00e9ment. Et cela se comprend facilement.<\/p>\n<p><strong>Le joueur a re\u00e7u des menaces de mort au lendemain de la d\u00e9faite de son \u00e9quipe \u00e0 domicile contre Alwarays Ready (0-2), lors de la premi\u00e8re journ\u00e9e de la phase de poules de la\u00a0Copa Libertadores.<\/strong><\/p>\n<h3><span style=\"color: #ff0000;\">\u00ab\u00a0On va te retrouver\u00a0\u00bb<\/span><\/h3>\n<p>\u00ab\u00a0<em>Ce n\u2019est qu\u2019une question de temps. Je ne sais pas ce qu\u2019on va faire, peut-\u00eatre te tuer. Je ne sais pas, mais on va te retrouver<\/em>\u00a0\u00bb, disait le message audio re\u00e7u par la famille de <strong>Ramos, plus de 600 matches avec le grand club de Sao Paulo.<\/strong><\/p>\n<p>\u00ab\u00a0<em>Le Sport Club Corinthians Paulista d\u00e9nonce avec v\u00e9h\u00e9mence les menaces de mort et de violence prof\u00e9r\u00e9es contre le gardien C\u00e1ssio et sa famille par le biais de messages envoy\u00e9s sur un r\u00e9seau social\u00a0<\/em>\u00bb, a r\u00e9agi le club dans un communiqu\u00e9.<\/p>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/menaces-de-mort-gardien-bresil-10027449.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Le club des Corinthians prend tr\u00e8s au s\u00e9rieux les menaces physiques dont sont victimes son gardien de but et sa famille. Le Br\u00e9silien Cassio Ramos, 34 ans (1 s\u00e9lection), a \u00e9t\u00e9 plac\u00e9 sous protection polici\u00e8re. La situation du gardien de but des Corinthians inqui\u00e8te \u00e9norm\u00e9ment. Et cela se comprend facilement. Le joueur a re\u00e7u &hellip;<\/p>\n","protected":false},"author":1,"featured_media":30671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-30670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2022\/04\/Cassio-Ramos.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/30670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=30670"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/30670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/30671"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=30670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=30670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=30670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}