{"id":29233,"date":"2022-03-20T16:17:47","date_gmt":"2022-03-20T16:17:47","guid":{"rendered":"http:\/\/www.tunimedia.tn\/fr\/tuchel-se-fait-un-sang-dencre\/"},"modified":"2022-03-20T16:17:47","modified_gmt":"2022-03-20T16:17:47","slug":"tuchel-se-fait-un-sang-dencre","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/tuchel-se-fait-un-sang-dencre\/","title":{"rendered":"Tuchel se fait un sang d&rsquo;encre"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nLe coach de Chelsea, Thomas Tuchel, \u00e9voque la situation difficile de son club. <\/p>\n<div>\n<p><strong>L\u2019entra\u00eeneur de Chelsea, Thomas Tuchel, admet que les plans de march\u00e9 estival de son \u00e9quipe pourraient \u00eatre affect\u00e9s par la vente du club.<\/strong>\u00a0Thomas Tuchel admet en effet que des retards pourraient perturber les plans de transferts estivaux d\u2019une formation qui comptaient parmi les plus riches d\u2019Europe apr\u00e8s les \u00e9v\u00e8nements r\u00e9cents dus \u00e0 l\u2019invasion de l\u2019Ukraine par la Russie.<\/p>\n<h2><span style=\"color: #ff0000;\">Tuchel tr\u00e8s inquiet pour Chelsea<\/span><\/h2>\n<p><strong>\u00ab\u00a0C\u2019est possible, mais aujourd\u2019hui je ne veux pas me concentrer sur les probl\u00e8mes.<\/strong> Peut-\u00eatre que \u00e7a va se passer comme \u00e7a, peut-\u00eatre que certains joueurs vont se d\u00e9cider pour quelque chose qu\u2019ils n\u2019auraient pas d\u00e9cid\u00e9 dans d\u2019autres situations.\u00a0Mais il y a beaucoup de \u00ab\u00a0si\u00a0\u00bb dans cette conversation. Nous esp\u00e9rons que le club va poursuivre son histoire, j\u2019ai confiance en notre capacit\u00e9 d\u2019adaptation et je suis convaincu de notre capacit\u00e9 \u00e0 trouver des solutions\u00a0\u00bb, a gliss\u00e9 le coach allemand face aux m\u00e9dias anglais.<\/p>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/tuchel-se-sang-dencre-10023583.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Le coach de Chelsea, Thomas Tuchel, \u00e9voque la situation difficile de son club. L\u2019entra\u00eeneur de Chelsea, Thomas Tuchel, admet que les plans de march\u00e9 estival de son \u00e9quipe pourraient \u00eatre affect\u00e9s par la vente du club.\u00a0Thomas Tuchel admet en effet que des retards pourraient perturber les plans de transferts estivaux d\u2019une formation qui comptaient &hellip;<\/p>\n","protected":false},"author":1,"featured_media":27625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-29233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2022\/02\/1645957464_Thomas-Tuchel-Chelsea.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/29233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=29233"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/29233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/27625"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=29233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=29233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=29233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}