{"id":21167,"date":"2021-12-07T10:38:04","date_gmt":"2021-12-07T10:38:04","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/quand-zanetti-a-failli-rejoindre-le-real-madrid\/"},"modified":"2021-12-07T10:38:04","modified_gmt":"2021-12-07T10:38:04","slug":"quand-zanetti-a-failli-rejoindre-le-real-madrid","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/quand-zanetti-a-failli-rejoindre-le-real-madrid\/","title":{"rendered":"Quand Zanetti a failli rejoindre le Real Madrid"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<p>\nJavier Zanetti, l\u00e9gende de l&rsquo;Inter Milan, confie qu&rsquo;il a failli rejoindre le Real Madrid par le pass\u00e9. <\/p>\n<div>\n<p>Le vice-pr\u00e9sident et ancien capitaine de l\u2019Inter, Javier Zanetti, a expliqu\u00e9 les raisons de sa d\u00e9cision de ne pas rejoindre le Real Madrid, alors que les deux parties \u00e9taient sur le point de trouver un accord.<strong> Zanetti s\u2019est rendu \u00e0 Madrid avec les Nerazzurri, qui affronteront le Real Madrid ce mardi au stade Santiago Bernabeu lors du dernier match de la phase de groupes de la Ligue des Champions.<\/strong><\/p>\n<h2><span style=\"color: #ff0000;\">Zanetti a failli devenir merengue<\/span><\/h2>\n<p>\u00ab\u00a0Oui, j\u2019\u00e9tais tr\u00e8s proche [de rejoindre le Real Madrid] et j\u2019ai d\u00e9j\u00e0 dit que je me sentais honor\u00e9 par l\u2019int\u00e9r\u00eat d\u2019un tel club. C\u2019\u00e9tait \u00e0 l\u2019\u00e9poque o\u00f9 Jorge Valdano \u00e9tait directeur sportif. Mais tout le monde conna\u00eet mon histoire et sait que l\u2019Inter est ma maison. C\u2019est pourquoi j\u2019ai d\u00e9cid\u00e9 de rester ici. Je m\u2019identifiais \u00e0 l\u2019Inter et le fait est que je jouais aussi pour un club avec beaucoup d\u2019histoire, m\u00eame si nous avons eu des difficult\u00e9s \u00e0 l\u2019\u00e9poque. Les choses ne se sont pas pass\u00e9es comme pr\u00e9vu et je ne voulais pas partir sans avoir laiss\u00e9 une trace.<strong> J\u2019\u00e9tais le capitaine et j\u2019avais une grande responsabilit\u00e9. Et je suis rest\u00e9\u00a0\u00bb, <\/strong>a-t-il confi\u00e9 \u00e0 <em>Marca<\/em>.<\/p>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/zanetti-a-failli-rejoindre-real-madrid-10003232.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Javier Zanetti, l\u00e9gende de l&rsquo;Inter Milan, confie qu&rsquo;il a failli rejoindre le Real Madrid par le pass\u00e9. Le vice-pr\u00e9sident et ancien capitaine de l\u2019Inter, Javier Zanetti, a expliqu\u00e9 les raisons de sa d\u00e9cision de ne pas rejoindre le Real Madrid, alors que les deux parties \u00e9taient sur le point de trouver un accord. Zanetti &hellip;<\/p>\n","protected":false},"author":1,"featured_media":21168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-21167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2021\/12\/zanetti.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/21167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=21167"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/21167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/21168"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=21167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=21167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=21167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}