{"id":102475,"date":"2025-06-26T21:28:24","date_gmt":"2025-06-26T21:28:24","guid":{"rendered":"https:\/\/www.tunimedia.tn\/fr\/neymar-ancelotti-sagace-deja-il-doit\/"},"modified":"2025-06-26T21:28:24","modified_gmt":"2025-06-26T21:28:24","slug":"neymar-ancelotti-sagace-deja-il-doit","status":"publish","type":"post","link":"https:\/\/tunimedia.tn\/fr\/neymar-ancelotti-sagace-deja-il-doit\/","title":{"rendered":"Neymar, Ancelotti s&rsquo;agace d\u00e9j\u00e0 : \u00ab Il doit&#8230; \u00bb"},"content":{"rendered":"<p> [ad_1]\n<\/p>\n<div data-live-id=\"articleContent.isLive\" data-live-value=\"17509685120\" data-live=\"0\" data-live-reload=\"1\">\n<p>Le compte \u00e0 rebours est d\u00e9j\u00e0 lanc\u00e9 : dans un an, le Br\u00e9sil<br \/>\nparticipera \u00e0 la Coupe du monde 2026 sur le sol nord-am\u00e9ricain. Un<br \/>\n\u00e9v\u00e9nement majeur pour la Sele\u00e7ao, nation la plus titr\u00e9e de<br \/>\nl\u2019histoire de la comp\u00e9tition avec ses 5 \u00e9toiles.<\/p>\n<p>Arriv\u00e9 il y a quelques semaines pour s\u2019attaquer \u00e0 un vaste<br \/>\nchantier apr\u00e8s deux ann\u00e9es tr\u00e8s d\u00e9licates, Carlo Ancelotti a du<br \/>\npain sur la planche. Le technicien italien veut se donner toutes<br \/>\nles chances de mener les Auriverde au sommet du football<br \/>\nmondial.<\/p>\n<div id=\"attachment_10237981\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.football365.fr\/wp-content\/uploads\/se\/2025\/05\/ICONSPORT_259381_0060.jpg\"><\/p>\n<div class=\"wrap-img\" id=\"wrap-img-10237981\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10237981\" class=\"size-full wp-image-10237981\" src=\"https:\/\/cdn.football365.fr\/wp-content\/uploads\/se\/2025\/05\/ICONSPORT_259381_0060.jpg\" alt=\"Neymar, l\u2019\u00e9nigme d\u2019Ancelotti : Une exclusion qui pourrait tout changer pour le Br\u00e9sil\" width=\"1280\" height=\"670\" srcset=\"https:\/\/cdn.football365.fr\/wp-content\/uploads\/se\/2025\/05\/ICONSPORT_259381_0060.jpg 1280w, https:\/\/cdn.football365.fr\/wp-content\/uploads\/se\/2025\/05\/ICONSPORT_259381_0060-300x157.jpg 300w, https:\/\/cdn.football365.fr\/wp-content\/uploads\/se\/2025\/05\/ICONSPORT_259381_0060-1024x536.jpg 1024w, https:\/\/cdn.football365.fr\/wp-content\/uploads\/se\/2025\/05\/ICONSPORT_259381_0060-768x402.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"\/><\/div>\n<p><\/a><\/p>\n<p id=\"caption-attachment-10237981\" class=\"wp-caption-text\">Carlo<br \/>\nAncelotti, nouveau s\u00e9lectionneur du Br\u00e9sil.<\/p>\n<\/div>\n<p>S\u2019il compte d\u00e9j\u00e0 sur les pr\u00e9sences de Vinicius, Rodrygo ou<br \/>\nencore Raphinha dans un secteur offensif bien fourni, l\u2019ancien<br \/>\nentra\u00eeneur du Real Madrid souhaite surtout s\u2019appuyer sur<br \/>\nNeymar.<\/p>\n<h2>Ancelotti avertit Neymar<\/h2>\n<p>Dans un entretien diffus\u00e9 sur les r\u00e9seaux sociaux de la<br \/>\nF\u00e9d\u00e9ration br\u00e9silienne de football, Carlo Ancelotti a fait passer<br \/>\nun message assez clair \u00e0 Neymar : la star devrait faire attention \u00e0<br \/>\nson hygi\u00e8ne de vie pour arriver \u00e0 100% au Mondial.<\/p>\n<p><em>\u00ab\u00a0Il doit bien se pr\u00e9parer et il a le temps de le<br \/>\nfaire. C\u2019est un joueur tr\u00e8s important pour nous en vue de la Coupe<br \/>\ndu monde en 2026\u00a0\u00bb<\/em>, a l\u00e2ch\u00e9 Carlo Ancelotti. Pour rappel,<br \/>\nNeymar vient de prolonger son contrat \u00e0 Santos jusqu\u2019en d\u00e9cembre<br \/>\n2025.<\/p>\n<\/div>\n[ad_2]\n<br \/><a href=\"https:\/\/www.football365.fr\/neymar-ancelotti-sagace-deja-il-doit-10244123.html?utm_source=rss_feed&#038;utm_medium=link&#038;utm_campaign=unknown\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Le compte \u00e0 rebours est d\u00e9j\u00e0 lanc\u00e9 : dans un an, le Br\u00e9sil participera \u00e0 la Coupe du monde 2026 sur le sol nord-am\u00e9ricain. Un \u00e9v\u00e9nement majeur pour la Sele\u00e7ao, nation la plus titr\u00e9e de l\u2019histoire de la comp\u00e9tition avec ses 5 \u00e9toiles. Arriv\u00e9 il y a quelques semaines pour s\u2019attaquer \u00e0 un vaste &hellip;<\/p>\n","protected":false},"author":1,"featured_media":102476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[350],"tags":[],"class_list":["post-102475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"jetpack_featured_media_url":"https:\/\/tunimedia.tn\/fr\/wp-content\/uploads\/2025\/06\/ICONSPORT_260965_0004-1.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/102475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/comments?post=102475"}],"version-history":[{"count":0,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/posts\/102475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media\/102476"}],"wp:attachment":[{"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/media?parent=102475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/categories?post=102475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunimedia.tn\/fr\/wp-json\/wp\/v2\/tags?post=102475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}